{"id":641,"date":"2022-04-12T09:14:46","date_gmt":"2022-04-12T09:14:46","guid":{"rendered":"https:\/\/ganacompartiendo.es\/?page_id=641"},"modified":"2022-06-23T12:43:49","modified_gmt":"2022-06-23T12:43:49","slug":"natalia","status":"publish","type":"page","link":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/","title":{"rendered":"Natalia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"641\" class=\"elementor elementor-641\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ade5d5f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ade5d5f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c43a1e1\" data-id=\"c43a1e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19a71e1 elementor-widget elementor-widget-image\" data-id=\"19a71e1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2400\" height=\"594\" src=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg\" class=\"attachment-full size-full wp-image-644\" alt=\"\" srcset=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg 2400w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios-300x74.jpg 300w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios-1024x253.jpg 1024w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios-768x190.jpg 768w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios-1536x380.jpg 1536w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios-2048x507.jpg 2048w\" sizes=\"(max-width: 2400px) 100vw, 2400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f6ae66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f6ae66\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c41a9a6\" data-id=\"c41a9a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-143bd6b elementor-widget elementor-widget-image\" data-id=\"143bd6b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"109\" src=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Gana-Compartiendo-300x109.jpg\" class=\"attachment-medium size-medium wp-image-648\" alt=\"\" srcset=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Gana-Compartiendo-300x109.jpg 300w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Gana-Compartiendo-1024x373.jpg 1024w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Gana-Compartiendo-768x280.jpg 768w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Gana-Compartiendo-1536x560.jpg 1536w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Gana-Compartiendo.jpg 1594w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-608af178 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"608af178\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2a666d71\" data-id=\"2a666d71\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c4be4b elementor-widget elementor-widget-image\" data-id=\"8c4be4b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"370\" height=\"440\" src=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/foto-retrato.jpg\" class=\"attachment-large size-large wp-image-564\" alt=\"\" srcset=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/foto-retrato.jpg 370w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/foto-retrato-252x300.jpg 252w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2d65ceb2\" data-id=\"2d65ceb2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3784dfc elementor-widget elementor-widget-heading\" data-id=\"3784dfc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Natalia Potapova<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43e1fac3 elementor-widget elementor-widget-heading\" data-id=\"43e1fac3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mi experiencia <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b2098 elementor-widget elementor-widget-text-editor\" data-id=\"77b2098\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Me siento feliz y agradecida de que me hayan dado la oportunidad de pertenecer a este maravilloso Club privado de Vacaciones.<\/p><p><br \/>Gracias a nuestro Club he conseguido ahorrar mucho en cada viaje, hasta un 50% de ahorro , llegando a viajar Gratis en Cruceros de lujo.<br \/>Adem\u00e1s ganamos ingresos y recibimos recompensas en nuestras vacaciones.<\/p><p><br \/>Tambi\u00e9n nos pagan por compartir y ayudar a otras personas a unirse a nuestro Club, darles la misma oportunidad que nos han dado a nosotros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5ff9d697\" data-id=\"5ff9d697\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ee84147 elementor-widget elementor-widget-heading\" data-id=\"4ee84147\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Est\u00e1s a un paso de formar parte de esta experiencia de viaje inigualable.<br><br> Completa el siguiente formulario y te enviaremos una clave de acceso que debes colocar en la secci\u00f3n de INSCRIBETE y as\u00ed podr\u00e1s unirte a nuestro Club de Viaje.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adc4e3b elementor-widget elementor-widget-wpforms\" data-id=\"adc4e3b\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container \" id=\"wpforms-1241\"><form id=\"wpforms-form-1241\" class=\"wpforms-validate wpforms-form\" data-formid=\"1241\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/641\" data-token=\"f59c9c895fc7209268611e229bf877e3\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1241-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-1241-field_4\">Nombre y Apellido <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1241-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-1241-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-1241-field_1\">Correo electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1241-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-1241-field_2-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-1241-field_2\">Tel\u00e9fono<\/label><input type=\"number\" pattern=\"\\d*\" id=\"wpforms-1241-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" ><\/div><div id=\"wpforms-1241-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-1241-field_3\">Comentarios<\/label><textarea id=\"wpforms-1241-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" ><\/textarea><\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"1241\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1241\" class=\"wpforms-submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30c7472e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30c7472e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1fbf0960\" data-id=\"1fbf0960\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3452b009\" data-id=\"3452b009\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15264eb5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"15264eb5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ganacompartiendo.es\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-home\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inicio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4ae6e4c\" data-id=\"4ae6e4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4384f16 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4384f16\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ganacompartiendo.es\/index.php\/socios\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-users\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Miembros<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5baa626\" data-id=\"5baa626\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff35818 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ff35818\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ganacompartiendo.es\/index.php\/natalia-afiliacion\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pen\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inscr\u00edbete<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-15a16cd6\" data-id=\"15a16cd6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c80a10 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9c80a10\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7491243\" data-id=\"7491243\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f23e409 elementor-widget elementor-widget-video\" data-id=\"f23e409\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/06\/WhatsApp-Video-2022-06-22-at-1.31.24-PM.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\" poster=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/photo_2022-04-11_17-55-47.jpg\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dbbbd83\" data-id=\"dbbbd83\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ead2e1b elementor-widget elementor-widget-image\" data-id=\"ead2e1b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"425\" src=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/02.jpg\" class=\"attachment-large size-large wp-image-673\" alt=\"\" srcset=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/02.jpg 567w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/02-300x225.jpg 300w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09a6d6b elementor-widget elementor-widget-image\" data-id=\"09a6d6b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"425\" src=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/05.jpg\" class=\"attachment-large size-large wp-image-676\" alt=\"\" srcset=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/05.jpg 567w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/05-300x225.jpg 300w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4a0bea2\" data-id=\"4a0bea2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cce9ee1 elementor-widget elementor-widget-image\" data-id=\"cce9ee1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"425\" src=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/01.jpg\" class=\"attachment-large size-large wp-image-672\" alt=\"\" srcset=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/01.jpg 567w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/01-300x225.jpg 300w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-966f427 elementor-widget elementor-widget-image\" data-id=\"966f427\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"425\" src=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/03.jpg\" class=\"attachment-large size-large wp-image-674\" alt=\"\" srcset=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/03.jpg 567w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/03-300x225.jpg 300w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65929f0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"65929f0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7878e77\" data-id=\"7878e77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caa597a elementor-widget elementor-widget-image\" data-id=\"caa597a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"425\" src=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/04.jpg\" class=\"attachment-large size-large wp-image-675\" alt=\"\" srcset=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/04.jpg 567w, https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/04-300x225.jpg 300w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-99a7be5\" data-id=\"99a7be5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3828035\" data-id=\"3828035\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Natalia Potapova Mi experiencia Me siento feliz y agradecida de que me hayan dado la oportunidad de pertenecer a este maravilloso Club privado de Vacaciones. Gracias a nuestro Club he conseguido ahorrar mucho en cada viaje, hasta un 50% de ahorro , llegando a viajar Gratis en Cruceros de lujo. Adem\u00e1s ganamos ingresos y recibimos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-641","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Natalia -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Natalia -\" \/>\n<meta property=\"og:description\" content=\"Natalia Potapova Mi experiencia Me siento feliz y agradecida de que me hayan dado la oportunidad de pertenecer a este maravilloso Club privado de Vacaciones. Gracias a nuestro Club he conseguido ahorrar mucho en cada viaje, hasta un 50% de ahorro , llegando a viajar Gratis en Cruceros de lujo. Adem\u00e1s ganamos ingresos y recibimos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-23T12:43:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/\",\"url\":\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/\",\"name\":\"Natalia -\",\"isPartOf\":{\"@id\":\"https:\/\/ganacompartiendo.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg\",\"datePublished\":\"2022-04-12T09:14:46+00:00\",\"dateModified\":\"2022-06-23T12:43:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#primaryimage\",\"url\":\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg\",\"contentUrl\":\"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg\",\"width\":2400,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ganacompartiendo.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Natalia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ganacompartiendo.es\/#website\",\"url\":\"https:\/\/ganacompartiendo.es\/\",\"name\":\"\",\"description\":\"Explore the globe with travel &amp; tourism\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ganacompartiendo.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Natalia -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/","og_locale":"es_ES","og_type":"article","og_title":"Natalia -","og_description":"Natalia Potapova Mi experiencia Me siento feliz y agradecida de que me hayan dado la oportunidad de pertenecer a este maravilloso Club privado de Vacaciones. Gracias a nuestro Club he conseguido ahorrar mucho en cada viaje, hasta un 50% de ahorro , llegando a viajar Gratis en Cruceros de lujo. Adem\u00e1s ganamos ingresos y recibimos [&hellip;]","og_url":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/","article_modified_time":"2022-06-23T12:43:49+00:00","og_image":[{"url":"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/","url":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/","name":"Natalia -","isPartOf":{"@id":"https:\/\/ganacompartiendo.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#primaryimage"},"image":{"@id":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#primaryimage"},"thumbnailUrl":"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg","datePublished":"2022-04-12T09:14:46+00:00","dateModified":"2022-06-23T12:43:49+00:00","breadcrumb":{"@id":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ganacompartiendo.es\/index.php\/natalia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#primaryimage","url":"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg","contentUrl":"https:\/\/ganacompartiendo.es\/wp-content\/uploads\/2022\/04\/Medida-Banner-socios.jpg","width":2400,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/ganacompartiendo.es\/index.php\/natalia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ganacompartiendo.es\/"},{"@type":"ListItem","position":2,"name":"Natalia"}]},{"@type":"WebSite","@id":"https:\/\/ganacompartiendo.es\/#website","url":"https:\/\/ganacompartiendo.es\/","name":"","description":"Explore the globe with travel &amp; tourism","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ganacompartiendo.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ganacompartiendo.es\/index.php\/wp-json\/wp\/v2\/pages\/641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ganacompartiendo.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ganacompartiendo.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ganacompartiendo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ganacompartiendo.es\/index.php\/wp-json\/wp\/v2\/comments?post=641"}],"version-history":[{"count":113,"href":"https:\/\/ganacompartiendo.es\/index.php\/wp-json\/wp\/v2\/pages\/641\/revisions"}],"predecessor-version":[{"id":1560,"href":"https:\/\/ganacompartiendo.es\/index.php\/wp-json\/wp\/v2\/pages\/641\/revisions\/1560"}],"wp:attachment":[{"href":"https:\/\/ganacompartiendo.es\/index.php\/wp-json\/wp\/v2\/media?parent=641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}